{"id":4114,"date":"2016-04-27T21:06:31","date_gmt":"2016-04-27T21:06:31","guid":{"rendered":"http:\/\/odontoapeles.com.br\/clinica-odontologica\/dentista\/zona-sul\/\/?p=4114"},"modified":"2020-01-30T03:04:35","modified_gmt":"2020-01-30T03:04:35","slug":"implantes-osseointegrados","status":"publish","type":"post","link":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/","title":{"rendered":"Implantes Osseointegrados"},"content":{"rendered":"<h4><span style=\"color: #008000;\"><strong>Implantes Osseointegrados:\u00a0<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong>Implantes osseointegrados<\/strong><\/span>\u00a0s\u00e3o estruturas de metal, normalmente de tit\u00e2nio, semelhantes a pinos ou parafusos, as quais s\u00e3o instalados no interior dos ossos dos maxilares por meio de uma cirurgia espec\u00edfica <strong>(fase cir\u00fargica)<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Podemos considerar os implantes\u00a0como sendo os substitutos das ra\u00edzes dent\u00e1rias naturais ausentes ou extra\u00eddas.<\/p>\n<div id=\"attachment_4116\" style=\"width: 269px\" class=\"wp-caption alignleft\"><a class=\"dt-single-image\" href=\"http:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\/\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\" data-dt-img-description=\"IMPLANTES DENT\u00c1RIOS\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-4116\" class=\"wp-image-4116 size-full\" title=\"Implantes Osseointegrados Zona Sul, Implantes Osseointegrados Zona Sul SP, Implantes Osseointegrados Zona Sul de SP, Implantes Osseointegrados Zona Sul de S\u00e3o Paulo, Implantes Osseointegrados S\u00e3o Paulo, Implantes Osseointegrados SP, Implantes Osseointegrados na Zona Sul, Implantes Osseointegrados na Zona Sul SP, Implantes Osseointegrados na Zona Sul de SP, Implantes Osseointegrados na Zona Sul de S\u00e3o Paulo, Implantes Osseointegrados em S\u00e3o Paulo, Implantes Osseointegrados em SP, Implantes Osseointegrados,\" src=\"http:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\" alt=\"Implantes Osseointegrados Zona Sul, Implantes Osseointegrados Zona Sul SP, Implantes Osseointegrados Zona Sul de SP, Implantes Osseointegrados Zona Sul de S\u00e3o Paulo, Implantes Osseointegrados S\u00e3o Paulo, Implantes Osseointegrados SP, Implantes Osseointegrados na Zona Sul, Implantes Osseointegrados na Zona Sul SP, Implantes Osseointegrados na Zona Sul de SP, Implantes Osseointegrados na Zona Sul de S\u00e3o Paulo, Implantes Osseointegrados em S\u00e3o Paulo, Implantes Osseointegrados em SP, Implantes Osseointegrados,\" width=\"259\" height=\"194\" \/><\/a><p id=\"caption-attachment-4116\" class=\"wp-caption-text\"><strong><span style=\"color: #008000;\">IMPLANTES\u00a0OSSEOINTEGRADOS<\/span><\/strong><\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Implantes <span style=\"text-decoration: underline;\">osseointegrados<\/span><\/strong>\u00a0bem realizados\u00a0funcionam como dentes naturais, pois al\u00e9m de restabelecerem a\u00a0apar\u00eancia est\u00e9tica, do paciente, devolvem ao mesmo suas demais fun\u00e7\u00f5es\u00a0bucais, parcial ou totalmente comprometidas, tais como a mastiga\u00e7\u00e3o e a fon\u00e9tica.<\/p>\n<p style=\"text-align: justify;\">A partir da puberdade, qualquer indiv\u00edduo pode submeter-se a tratamentos de implante dent\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Decorrido o tempo de osseointegra\u00e7\u00e3o (tempo necess\u00e1rio para a uni\u00e3o est\u00e1vel e funcional entre os implantes e os ossos), ser\u00e3o\u00a0confeccionadas sobre os implantes, agora fixados e estabilizados, pr\u00f3teses em substitui\u00e7\u00f5es aos dentes naturais perdidos, as quais\u00a0denominamos pr\u00f3teses sobre implantes <strong>(fase prot\u00e9tica)<\/strong>.<\/p>\n<p style=\"text-align: justify;\">As pr\u00f3teses sobre implantes podem apresentar diversos modelos e formatos, sempre de acordo com as necessidades de cada caso individual.<\/p>\n<p style=\"text-align: justify;\">Tais pr\u00f3teses proporcionar\u00e3o ao paciente muito mais confian\u00e7a e seguran\u00e7a durante o exerc\u00edcio de todas as suas\u00a0fun\u00e7\u00f5es bucais, principalmente, durante o ato da mastiga\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Dependendo do n\u00famero de dentes que as constituem, as pr\u00f3teses sobre implantes podem se classificadas como unit\u00e1rias, parciais ou totais.<\/p>\n<p style=\"text-align: justify;\">Quanto \u00e0 possibilidade de serem retiradas da boca para higieniza\u00e7\u00e3o, s\u00e3o classificadas como fixas ou m\u00f3veis.<\/p>\n<p style=\"text-align: justify;\">\u00c9 importante salientar que tratamentos com\u00a0implantes\u00a0apresentam alt\u00edssimas taxas de sucesso, mas desde que corretamente\u00a0indicados.<\/p>\n<p style=\"text-align: justify;\">A presen\u00e7a de ossos maxilares volumosos, a aus\u00eancia de infec\u00e7\u00f5es dent\u00e1rias e gengivais e a boa condi\u00e7\u00e3o de sa\u00fade geral do paciente s\u00e3o fatores que contribuem para o \u00eaxito do tratamento com implantes.<\/p>\n<p style=\"text-align: justify;\">Ao contr\u00e1rio, ossos maxilares atrofiados, dentes e gengivas infectados, assim como a pr\u00e9-exist\u00eancia de doen\u00e7as sist\u00eamicas no paciente, como a osteoporose e a diabete, diminuem suas chances de sucesso.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><strong><a class=\"dt-single-image\" href=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png\" data-dt-img-description=\"\"><img decoding=\"async\" class=\"aligncenter wp-image-10843 size-full\" title=\"SP,\u00a0 Cl\u00ednica Odontol\u00f3gica na Zona Sul SP\" src=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png\" alt=\"Odontologia Apeles Lemos - 5563-5471,\u00a0 Cl\u00ednica Odontol\u00f3gica Zona Sul SP\" width=\"910\" height=\"272\" srcset=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png 910w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-300x90.png 300w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-768x230.png 768w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-600x179.png 600w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/><\/a><\/strong><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<\/strong><\/span><\/span><\/p>\n<div class=\"caldera-grid\" id=\"caldera_form_1\" data-cf-ver=\"1.9.7\" data-cf-form-id=\"CF5b00382b5a25d\"><div id=\"caldera_notices_1\" data-spinner=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-admin\/images\/spinner.gif\"><\/div><form data-instance=\"1\" class=\"CF5b00382b5a25d caldera_forms_form cfajax-trigger\" method=\"POST\" enctype=\"multipart\/form-data\" id=\"CF5b00382b5a25d_1\" data-form-id=\"CF5b00382b5a25d\" aria-label=\"FALE CONOSCO\" data-target=\"#caldera_notices_1\" data-template=\"#cfajax_CF5b00382b5a25d-tmpl\" data-cfajax=\"CF5b00382b5a25d\" data-load-element=\"_parent\" data-load-class=\"cf_processing\" data-post-disable=\"0\" data-action=\"cf_process_ajax_submit\" data-request=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cf-api\/CF5b00382b5a25d\" data-hiderows=\"true\">\r\n<input type=\"hidden\" id=\"_cf_verify_CF5b00382b5a25d\" name=\"_cf_verify\" value=\"89d6600eb4\"  data-nonce-time=\"1778685818\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/4114\" \/><div id=\"cf2-CF5b00382b5a25d_1\"><\/div><input type=\"hidden\" name=\"_cf_frm_id\" value=\"CF5b00382b5a25d\">\r\n<input type=\"hidden\" name=\"_cf_frm_ct\" value=\"1\">\r\n<input type=\"hidden\" name=\"cfajax\" value=\"CF5b00382b5a25d\">\r\n<input type=\"hidden\" name=\"_cf_cr_pst\" value=\"4114\">\r\n<div class=\"hide\" style=\"display:none; overflow:hidden;height:0;width:0;\">\r\n<label>Nome<\/label><input type=\"text\" name=\"name\" value=\"\" autocomplete=\"off\">\r\n<\/div><div id=\"CF5b00382b5a25d_1-row-1\"  class=\"row  first_row\"><div  class=\"col-sm-12  single\"><div class=\"\"><\/div><\/div><\/div><div id=\"CF5b00382b5a25d_1-row-2\"  class=\"row \"><div  class=\"col-sm-4  first_col\"><div data-field-wrapper=\"fld_8768091\" class=\"form-group\" id=\"fld_8768091_1-wrap\">\r\n\t<label id=\"fld_8768091Label\" for=\"fld_8768091_1\" class=\"control-label\">Nome <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_8768091\" class=\" form-control\" id=\"fld_8768091_1\" name=\"fld_8768091\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_8768091Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_9286608\" class=\"form-group\" id=\"fld_9286608_1-wrap\">\r\n\t<label id=\"fld_9286608Label\" for=\"fld_9286608_1\" class=\"control-label\">WhatsApp<\/label>\r\n\t<div class=\"\">\r\n\t\t<input    type=\"text\" data-field=\"fld_9286608\" class=\" form-control\" id=\"fld_9286608_1\" name=\"fld_9286608\" value=\"\" data-type=\"text\"   aria-labelledby=\"fld_9286608Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<\/div><div  class=\"col-sm-4 \"><div data-field-wrapper=\"fld_9970286\" class=\"form-group\" id=\"fld_9970286_1-wrap\">\r\n\t<label id=\"fld_9970286Label\" for=\"fld_9970286_1\" class=\"control-label\">Telefone <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_9970286\" class=\" form-control\" id=\"fld_9970286_1\" name=\"fld_9970286\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_9970286Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_8026901\" class=\"form-group\" id=\"fld_8026901_1-wrap\">\r\n\t<label id=\"fld_8026901Label\" for=\"fld_8026901_1\" class=\"control-label\">Como nos Conheceu?<\/label>\r\n\t<div class=\"\">\r\n\t\t<select name=\"fld_8026901\" value=\"opt1754659\" data-field=\"fld_8026901\" class=\"form-control\" id=\"fld_8026901_1\"    aria-labelledby=\"fld_8026901Label\" >\n\t\t\t\t\t\t\t<option value=\"Google\" selected=\"selected\" data-calc-value=\"Google\" >\n\t\t\t\t\t\tGoogle\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Facebook\"  data-calc-value=\"Facebook\" >\n\t\t\t\t\t\tFacebook\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Instagram\"  data-calc-value=\"Instagram\" >\n\t\t\t\t\t\tInstagram\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Indica\u00e7\u00e3o\"  data-calc-value=\"Indica\u00e7\u00e3o\" >\n\t\t\t\t\t\tIndica\u00e7\u00e3o\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Placa\"  data-calc-value=\"Placa\" >\n\t\t\t\t\t\tPlaca\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Outros\"  data-calc-value=\"Outros\" >\n\t\t\t\t\t\tOutros\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t<\/div>\r\n<\/div>\r\n<\/div><div  class=\"col-sm-4  last_col\"><div data-field-wrapper=\"fld_6009157\" class=\"form-group\" id=\"fld_6009157_1-wrap\">\r\n\t<label id=\"fld_6009157Label\" for=\"fld_6009157_1\" class=\"control-label\">Endere\u00e7o de E-mail <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"email\" data-field=\"fld_6009157\" class=\" form-control\" id=\"fld_6009157_1\" name=\"fld_6009157\" value=\"\" data-type=\"email\" aria-required=\"true\"   aria-labelledby=\"fld_6009157Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_2601416\" class=\"form-group\" id=\"fld_2601416_1-wrap\">\r\n\t<label id=\"fld_2601416Label\" for=\"fld_2601416_1\" class=\"control-label\">Que Tratamento Deseja Realizar?<\/label>\r\n\t<div class=\"\">\r\n\t\t<select name=\"fld_2601416\" value=\"\" data-field=\"fld_2601416\" class=\"form-control\" id=\"fld_2601416_1\"    aria-labelledby=\"fld_2601416Label\" >\n\t\t<option value=\"\"><\/option>\r\n\t\t\t\t\t<option value=\"Harmoniza\u00e7\u00e3o Orofacial\"  data-calc-value=\"Harmoniza\u00e7\u00e3o Orofacial\" >\n\t\t\t\t\t\tHarmoniza\u00e7\u00e3o Orofacial\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Botox e Preenchimento Facial\"  data-calc-value=\"Botox e Preenchimento Facial\" >\n\t\t\t\t\t\tBotox e Preenchimento Facial\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Bichectomia\"  data-calc-value=\"Bichectomia\" >\n\t\t\t\t\t\tBichectomia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Lipo de Papada\"  data-calc-value=\"Lipo de Papada\" >\n\t\t\t\t\t\tLipo de Papada\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Jato de Plasma\"  data-calc-value=\"Jato de Plasma\" >\n\t\t\t\t\t\tJato de Plasma\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Odontologia Est\u00e9tica\"  data-calc-value=\"Odontologia Est\u00e9tica\" >\n\t\t\t\t\t\tOdontologia Est\u00e9tica\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Rinomodela\u00e7\u00e3o\"  data-calc-value=\"Rinomodela\u00e7\u00e3o\" >\n\t\t\t\t\t\tRinomodela\u00e7\u00e3o\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Implantes Dent\u00e1rios\"  data-calc-value=\"Implantes Dent\u00e1rios\" >\n\t\t\t\t\t\tImplantes Dent\u00e1rios\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Clareamento Dental\"  data-calc-value=\"Clareamento Dental\" >\n\t\t\t\t\t\tClareamento Dental\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Ortodontia\"  data-calc-value=\"Ortodontia\" >\n\t\t\t\t\t\tOrtodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Endodontia\"  data-calc-value=\"Endodontia\" >\n\t\t\t\t\t\tEndodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Pr\u00f3tese Dental\"  data-calc-value=\"Pr\u00f3tese Dental\" >\n\t\t\t\t\t\tPr\u00f3tese Dental\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Periodontia\"  data-calc-value=\"Periodontia\" >\n\t\t\t\t\t\tPeriodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Cirurgia Oral\"  data-calc-value=\"Cirurgia Oral\" >\n\t\t\t\t\t\tCirurgia Oral\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t<\/div>\r\n<\/div>\r\n<\/div><\/div><div id=\"CF5b00382b5a25d_1-row-3\"  class=\"row \"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_8340154\" class=\"form-group\" id=\"fld_8340154_1-wrap\">\r\n\t<label id=\"fld_8340154Label\" for=\"fld_8340154_1\" class=\"control-label\">Sua Mensagem<\/label>\r\n\t<div class=\"\">\r\n\t\t<textarea name=\"fld_8340154\" value=\"\" data-field=\"fld_8340154\" class=\"form-control\" id=\"fld_8340154_1\" rows=\"4\"    aria-labelledby=\"fld_8340154Label\" ><\/textarea>\n\t\t\t<\/div>\r\n<\/div>\r\n<div class=\"\"><p><\/p>\n<\/div><\/div><\/div><div id=\"CF5b00382b5a25d_1-row-4\"  class=\"row  last_row\"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_7908577\" class=\"form-group\" id=\"fld_7908577_1-wrap\">\r\n<div class=\"\">\r\n\t<input  class=\"btn btn-default\" type=\"submit\" name=\"fld_7908577\" id=\"fld_7908577_1\" value=\"Enviar Mensagem\" data-field=\"fld_7908577\"  >\n<\/div>\r\n<\/div>\r\n\t<input class=\"button_trigger_1\" type=\"hidden\" name=\"fld_7908577\" id=\"fld_7908577_1_btn\" value=\"\" data-field=\"fld_7908577\"  \/>\n<\/div><\/div><\/form>\r\n<\/div>\r\n\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><strong>\u00a0<\/strong><\/span><\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Implantes Osseointegrados, S\u00e3o Paulo, em S\u00e3o Paulo, SP, em SP, Zona Sul,\u00a0na Zona Sul,\u00a0Zona Sul SP, na Zona Sul SP, Zona Sul de SP, na Zona Sul de SP, Zona Sul de S\u00e3o Paulo, na Zona Sul de S\u00e3o Paulo, American\u00f3polis, Interlagos, Moema, Santo Amaro, Socorro, Avenida Cupec\u00ea, Avenida Interlagos, Avenida Nossa Senhora do Sabar\u00e1, Avenida Sargento Geraldo Santana, Avenida Washington Luiz, Avenida Yervant, Avenida Yervant Kissajikian, Campininha, Casa Palma, Ch\u00e1cara Flora, Ch\u00e1cara Santo Antonio, Cidade Ademar, Cidade Domitila, Cidade Dutra, Cidade J\u00falia, Cidade Leonor, Cidade Vargas, Cupec\u00ea, Granja Julieta, Nossa Senhora do Sabar\u00e1, Pedreira, Sa\u00fade, Vila Aeroporto, Vila Andrade, Vila Campestre, Vila Campo Grande, Vila Capela, Vila Castelo, Vila Celeste, Vila Clara, Vila Clementino, Vila Constan\u00e7a, Vila do Castelo, Vila do Cruzeiro, Vila \u00c9lida, Vila Cruzeiro, Vila Emir, Vila Facchini, Vila Filomena, Vila Guarani, Vila Imp\u00e9rio, Vila Inglesa, Vila Jabaquara, Vila Joaniza, Vila Maiara, Vila Marari, Vila Mascote, Vila Mira, Vila Mission\u00e1ria, Vila Nova Caled\u00f4nia, Vila Nova Sabar\u00e1, Vila Romano, Vila Rubi, Vila Santa Catarina, Vila S\u00e3o Jos\u00e9, Vila Socorro, Vila Cabral, Washington Luiz, Yervant, Campo Belo, Graja\u00fa, Jabaquara, Jardim Aeroporto, Jardim Alto Congonhas, Jardim Alvorada, Jardim Anchieta, Jardim B\u00e9lgica, Jardim Bom Clima, Jardim Bransley, Jardim Campina, Jardim Castelo, Jardim Cid\u00e1lia, Jardim Cl\u00e9lia, Jardim Cons\u00f3rcio, Jardim Cupec\u00ea, Jardim da Sa\u00fade, Jardim das Oliveiras, Jardim do Carmo, Jardim dos Prados, Jardim Ernestina, Jardim Gra\u00fana, Jardim Ip\u00ea, Jardim Itacolomi, Jardim Itapura, Jardim Los Angeles, Jardim Lourdes, Jardim Luanda, Jardim Luso, Jardim Manac\u00e1, Jardim Marajoara, Jardim Martini, Jardim Miriam, Jardim Niter\u00f3i, \u00a0Jardim Nosso Lar, Jardim Olinda, Jardim Oliveira, Jardim Orly, Jardim Pedreira, Jardim Prud\u00eancia, Jardim Santo Antonio, Jardim S\u00e3o Carlos, Jardim S\u00e3o Jorge, Jardim Sat\u00e9lite, Jardim Scaff, Jardim Selma, Jardim Sofia, Jardim Suzana, Jardim Taquaral, Jardim Uberaba, Jardim Ubirajara, Jardim Umuarama, Jurubatuba, Parque Cocaia, Parque Colonial, Parque Dorot\u00e9ia, perto do Col\u00e9gio 25 de Mar\u00e7o, perto do Col\u00e9gio Santa Maria, perto do Leroy Merlin Interlagos, perto do Makro Interlagos, perto do Mercado Extra Interlagos, perto do Shopping Interlagos, perto do Shopping Interlar, perto do Shopping Interlar Interlagos, perto do Aeroporto de Congonhas, pr\u00f3ximo ao Col\u00e9gio 25 de Mar\u00e7o, pr\u00f3ximo ao Col\u00e9gio Santa Maria, pr\u00f3ximo ao Leroy Merlin Interlagos, pr\u00f3ximo ao Makro Interlagos, pr\u00f3ximo ao Mercado Extra Interlagos, pr\u00f3ximo ao Shopping Interlagos, pr\u00f3ximo ao Shopping Interlar, pr\u00f3ximo ao Shopping Interlar Interlagos, pr\u00f3ximo ao Aeroporto de Congonhas,<\/strong><\/span><\/h2>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Implantes Osseointegrados, S\u00e3o Paulo, em S\u00e3o Paulo, SP, em SP, Zona Sul,\u00a0na Zona Sul,\u00a0Zona Sul SP, na Zona Sul SP, Zona Sul de SP, na Zona Sul de SP, Zona Sul de S\u00e3o Paulo, na Zona Sul de S\u00e3o Paulo, American\u00f3polis, Interlagos, Moema, Santo Amaro, Socorro, Avenida Cupec\u00ea, Avenida Interlagos, Avenida Nossa Senhora do Sabar\u00e1, Avenida Sargento Geraldo Santana, Avenida Washington Luiz, Avenida Yervant, Avenida Yervant Kissajikian, Campininha, Casa Palma, Ch\u00e1cara Flora, Ch\u00e1cara Santo Antonio, Cidade Ademar, Cidade Domitila, Cidade Dutra, Cidade J\u00falia, Cidade Leonor, Cidade Vargas, Cupec\u00ea, Granja Julieta, Nossa Senhora do Sabar\u00e1, Pedreira, Sa\u00fade, Vila Aeroporto, Vila Andrade, Vila Campestre, Vila Campo Grande, Vila Capela, Vila Castelo, Vila Celeste, Vila Clara, Vila Clementino, Vila Constan\u00e7a, Vila do Castelo, Vila do Cruzeiro, Vila \u00c9lida, Vila Cruzeiro, Vila Emir, Vila Facchini, Vila Filomena, Vila Guarani, Vila Imp\u00e9rio, Vila Inglesa, Vila Jabaquara, Vila Joaniza, Vila Maiara, Vila Marari, Vila Mascote, Vila Mira, Vila Mission\u00e1ria, Vila Nova Caled\u00f4nia, Vila Nova Sabar\u00e1, Vila Romano, Vila Rubi, Vila Santa Catarina, Vila S\u00e3o Jos\u00e9, Vila Socorro, Vila Cabral, Washington Luiz, Yervant, Campo Belo, Graja\u00fa, Jabaquara, Jardim Aeroporto, Jardim Alto Congonhas, Jardim Alvorada, Jardim Anchieta, Jardim B\u00e9lgica, Jardim Bom Clima, Jardim Bransley, Jardim Campina, Jardim Castelo, Jardim Cid\u00e1lia, Jardim Cl\u00e9lia, Jardim Cons\u00f3rcio, Jardim Cupec\u00ea, Jardim da Sa\u00fade, Jardim das Oliveiras, Jardim do Carmo, Jardim dos Prados, Jardim Ernestina, Jardim Gra\u00fana, Jardim Ip\u00ea, Jardim Itacolomi, Jardim Itapura, Jardim Los Angeles, Jardim Lourdes, Jardim Luanda, Jardim Luso, Jardim Manac\u00e1, Jardim Marajoara, Jardim Martini, Jardim Miriam, Jardim Niter\u00f3i, \u00a0Jardim Nosso Lar, Jardim Olinda, Jardim Oliveira, Jardim Orly, Jardim Pedreira, Jardim Prud\u00eancia, Jardim Santo Antonio, Jardim S\u00e3o Carlos, Jardim S\u00e3o Jorge, Jardim Sat\u00e9lite, Jardim Scaff, Jardim Selma, Jardim Sofia, Jardim Suzana, Jardim Taquaral, Jardim Uberaba, Jardim Ubirajara, Jardim Umuarama, Jurubatuba, Parque Cocaia, Parque Colonial, Parque Dorot\u00e9ia, perto do Col\u00e9gio 25 de Mar\u00e7o, perto do Col\u00e9gio Santa Maria, perto do Leroy Merlin Interlagos, perto do Makro Interlagos, perto do Mercado Extra Interlagos, perto do Shopping Interlagos, perto do Shopping Interlar, perto do Shopping Interlar Interlagos, perto do Aeroporto de Congonhas, pr\u00f3ximo ao Col\u00e9gio 25 de Mar\u00e7o, pr\u00f3ximo ao Col\u00e9gio Santa Maria, pr\u00f3ximo ao Leroy Merlin Interlagos, pr\u00f3ximo ao Makro Interlagos, pr\u00f3ximo ao Mercado Extra Interlagos, pr\u00f3ximo ao Shopping Interlagos, pr\u00f3ximo ao Shopping Interlar, pr\u00f3ximo ao Shopping Interlar Interlagos, pr\u00f3ximo ao Aeroporto de Congonhas,<\/strong><\/span><\/h2>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul de SP,\u00a0<\/strong><strong>Implantes Osseointegrados\u00a0<\/strong><strong>na Zona Sul de SP,\u00a0<\/strong><strong>Implantes Osseointegrados\u00a0<\/strong><strong>Zona Sul de S\u00e3o Paulo,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul de S\u00e3o Paulo,<\/strong><\/span><\/h2>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul de SP,\u00a0<\/strong><strong>Implantes Osseointegrados\u00a0<\/strong><strong>na Zona Sul de SP,\u00a0<\/strong><strong>Implantes Osseointegrados\u00a0<\/strong><strong>Zona Sul de S\u00e3o Paulo,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul de S\u00e3o Paulo,<\/strong><\/span><\/h2>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>na Zona Sul SP,\u00a0<\/strong><strong>Implantes Osseointegrados<\/strong><strong>\u00a0<\/strong><strong>Zona Sul de S\u00e3o Paulo, <\/strong><strong>Implantes Osseointegrados\u00a0<\/strong><strong>na Zona Sul de S\u00e3o Paulo,\u00a0<\/strong><\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">&#8211; SP,<\/span><\/h2>\n<h2><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Implantes Osseointegrados:\u00a0 Implantes osseointegrados\u00a0s\u00e3o estruturas de metal, normalmente de tit\u00e2nio, semelhantes a pinos ou parafusos, as quais s\u00e3o instalados no interior dos ossos dos maxilares por meio de uma cirurgia espec\u00edfica (fase cir\u00fargica). Podemos considerar os implantes\u00a0como sendo os substitutos das ra\u00edzes dent\u00e1rias naturais ausentes ou extra\u00eddas. Implantes osseointegrados\u00a0bem realizados\u00a0funcionam como dentes naturais, pois al\u00e9m&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-odontologicos","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Implantes Osseointegrados Zona Sul SP - Odontologia Apeles Lemos - 5563.5471<\/title>\n<meta name=\"description\" content=\"Implantes Osseointegrados s\u00e3o cilindros met\u00e1licos de tit\u00e2nio fixados cirurgicamente nos ossos maxilares a fim de de repor dentes ausentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991\"},\"headline\":\"Implantes Osseointegrados\",\"datePublished\":\"2016-04-27T21:06:31+00:00\",\"dateModified\":\"2020-01-30T03:04:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\"},\"wordCount\":1369,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\",\"articleSection\":[\"Artigos Odontol\u00f3gicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\",\"name\":\"Implantes Osseointegrados Zona Sul SP - Odontologia Apeles Lemos - 5563.5471\",\"isPartOf\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\",\"datePublished\":\"2016-04-27T21:06:31+00:00\",\"dateModified\":\"2020-01-30T03:04:35+00:00\",\"description\":\"Implantes Osseointegrados s\u00e3o cilindros met\u00e1licos de tit\u00e2nio fixados cirurgicamente nos ossos maxilares a fim de de repor dentes ausentes.\",\"breadcrumb\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\",\"contentUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg\",\"width\":259,\"height\":194,\"caption\":\"IMPLANTES DENT\u00c1RIOS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Implantes Osseointegrados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\",\"name\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"description\":\"Refer\u00eancia h\u00e1 30 anos em Odontologia, Cl\u00ednica Odontol\u00f3gica, Cl\u00ednica Dent\u00e1ria e Dentista Zona Sul SP. Whats App: 9 4624-0000. Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"publisher\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\",\"name\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png\",\"contentUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png\",\"width\":443,\"height\":190,\"caption\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/odontoapeles\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991\",\"name\":\"administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g\",\"caption\":\"administrador\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Implantes Osseointegrados Zona Sul SP - Odontologia Apeles Lemos - 5563.5471","description":"Implantes Osseointegrados s\u00e3o cilindros met\u00e1licos de tit\u00e2nio fixados cirurgicamente nos ossos maxilares a fim de de repor dentes ausentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/","twitter_misc":{"Escrito por":"administrador","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#article","isPartOf":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/"},"author":{"name":"administrador","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991"},"headline":"Implantes Osseointegrados","datePublished":"2016-04-27T21:06:31+00:00","dateModified":"2020-01-30T03:04:35+00:00","mainEntityOfPage":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/"},"wordCount":1369,"commentCount":2,"publisher":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage"},"thumbnailUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg","articleSection":["Artigos Odontol\u00f3gicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/","name":"Implantes Osseointegrados Zona Sul SP - Odontologia Apeles Lemos - 5563.5471","isPartOf":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage"},"thumbnailUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg","datePublished":"2016-04-27T21:06:31+00:00","dateModified":"2020-01-30T03:04:35+00:00","description":"Implantes Osseointegrados s\u00e3o cilindros met\u00e1licos de tit\u00e2nio fixados cirurgicamente nos ossos maxilares a fim de de repor dentes ausentes.","breadcrumb":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#primaryimage","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg","contentUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2016\/04\/Implantes-Dent\u00e1rios.jpg","width":259,"height":194,"caption":"IMPLANTES DENT\u00c1RIOS"},{"@type":"BreadcrumbList","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/implantes-osseointegrados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/"},{"@type":"ListItem","position":2,"name":"Implantes Osseointegrados"}]},{"@type":"WebSite","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/","name":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","description":"Refer\u00eancia h\u00e1 30 anos em Odontologia, Cl\u00ednica Odontol\u00f3gica, Cl\u00ednica Dent\u00e1ria e Dentista Zona Sul SP. Whats App: 9 4624-0000. Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","publisher":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization","name":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png","contentUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png","width":443,"height":190,"caption":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/odontoapeles"]},{"@type":"Person","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991","name":"administrador","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g","caption":"administrador"}}]}},"_links":{"self":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/4114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/comments?post=4114"}],"version-history":[{"count":0,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/4114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/media\/4116"}],"wp:attachment":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/media?parent=4114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/categories?post=4114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/tags?post=4114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}