{"id":16307,"date":"2021-07-04T23:48:52","date_gmt":"2021-07-04T23:48:52","guid":{"rendered":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/?p=16307"},"modified":"2021-07-06T02:06:56","modified_gmt":"2021-07-06T02:06:56","slug":"cuidados-pos-extracao-dentaria","status":"publish","type":"post","link":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/","title":{"rendered":"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria"},"content":{"rendered":"<h4><strong><span style=\"color: #0000ff;\">Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria &#8211; Introdu\u00e7\u00e3o:<\/span><\/strong><\/h4>\n<p style=\"text-align: justify;\">Os cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria devem ser muito bem detalhados pelo cirurgi\u00e3o-dentista, logo ap\u00f3s a conclus\u00e3o da cirurgia.<\/p>\n<div id=\"attachment_16311\" style=\"width: 269px\" class=\"wp-caption alignleft\"><a class=\"dt-pswp-item\" href=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/alveolo.jpg\" data-dt-img-description=\"CAVIDADE \u00d3SSEA VAZIA\" data-large_image_width=\"259\" data-large_image_height=\"194\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-16311\" class=\"wp-image-16311 size-full\" title=\"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria zona sul sp\" src=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/alveolo.jpg\" alt=\"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria zona sul sp\" width=\"259\" height=\"194\" srcset=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/alveolo.jpg 259w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/alveolo-16x12.jpg 16w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/a><p id=\"caption-attachment-16311\" class=\"wp-caption-text\"><strong><span style=\"color: #ff6600;\">CAVIDADE \u00d3SSEA VAZIA<\/span><\/strong><\/p><\/div>\n<p style=\"text-align: justify;\">Ap\u00f3s a extra\u00e7\u00e3o de um dente, a cicatriza\u00e7\u00e3o come\u00e7a imediatamente com o preenchimento do nosso pr\u00f3prio sangue no interior da cavidade \u00f3ssea deixada vazia pela raiz do dente extra\u00eddo.<\/p>\n<p style=\"text-align: justify;\">Como resultado desse processo natural de repara\u00e7\u00e3o que logo se inicia, ocorrer\u00e1 a forma\u00e7\u00e3o de um co\u00e1gulo sangu\u00edneo no interior do osso da regi\u00e3o do dente extra\u00eddo.<\/p>\n<p style=\"text-align: justify;\">Esse co\u00e1gulo sangu\u00edneo, ao preencher o osso vazio, protege o mesmo, evitando que seja invadido por bact\u00e9rias bucais e que sirva de dep\u00f3sito de res\u00edduos alimentares, impedindo a infec\u00e7\u00e3o p\u00f3s-operat\u00f3ria.<\/p>\n<p style=\"text-align: justify;\">Todos os esfor\u00e7os do paciente no p\u00f3s-operat\u00f3rio da extra\u00e7\u00e3o dent\u00e1ria devem ser direcionados no sentido de n\u00e3o promover situa\u00e7\u00f5es intra ou extra-bucais que possam agitar ou gerar esfor\u00e7os que possam resultar no deslocamento ou na dissolu\u00e7\u00e3o do co\u00e1gulo sangu\u00edneo.<\/p>\n<p style=\"text-align: justify;\">Ao contr\u00e1rio, o co\u00e1gulo deve ser preservado para que se consolide durante o processo de cicatriza\u00e7\u00e3o, culminando na forma\u00e7\u00e3o de gengiva e osso no local do dente extra\u00eddo.<\/p>\n<p style=\"text-align: justify;\">A perda do co\u00e1gulo sangu\u00edneo pode gerar complica\u00e7\u00f5es p\u00f3s-operat\u00f3rias graves, resultando em inflama\u00e7\u00f5es e infec\u00e7\u00f5es muito dolorosas.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong><span style=\"color: #0000ff;\">Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Recomendados:<\/span><\/strong><\/h4>\n<p style=\"text-align: justify;\">1 &#8211; Evitar falar muito nos tr\u00eas primeiros dias;<\/p>\n<p style=\"text-align: justify;\">2 &#8211; Ap\u00f3s o t\u00e9rmino da cirurgia \u00e9 importante n\u00e3o fazer esfor\u00e7os na regi\u00e3o bucal, de modo a evitar desconforto, dor, hemorragia e incha\u00e7o na \u00e1rea do dente extra\u00eddo;<\/p>\n<p style=\"text-align: justify;\">3 &#8211; Ficar em repouso o maior tempo poss\u00edvel nos tr\u00eas primeiros dias;<\/p>\n<p style=\"text-align: justify;\">4. Manter a cabe\u00e7a mais elevada do que o resto do corpo por um per\u00edodo de 24 horas ap\u00f3s a cirurgia de extra\u00e7\u00e3o;<\/p>\n<p style=\"text-align: justify;\">5 &#8211; Evitar exposi\u00e7\u00e3o ao sol, carregar objetos pesados, esfor\u00e7os e atividades f\u00edsicas, al\u00e9m de banhos muito quentes nos 5 primeiros dias;<\/p>\n<p style=\"text-align: justify;\">6 &#8211; Evitar\u00a0 ingerir alimentos quentes nos primeiros dois ou tr\u00eas dias ap\u00f3s a cirurgia, dando prefer\u00eancia aos alimentos frios, gelados ou em temperatura ambiente;<\/p>\n<p style=\"text-align: justify;\">7 &#8211; A alimenta\u00e7\u00e3o deve ser consistente, por\u00e9m l\u00edquida, pastosa ou pouco densa durante dois ou tr\u00eas primeiros dias para n\u00e3o ferir a regi\u00e3o operada. leite, sucos, vitaminas, sorvetes, iogurtes, gelatina, sopas, pur\u00eas, macarr\u00e3o e alimentos batidos no liquidificador;<\/p>\n<p style=\"text-align: justify;\">8 &#8211; A hidrata\u00e7\u00e3o \u00e9 importante, portanto recomenda-se ingerir bastante \u00e1gua;<\/p>\n<p style=\"text-align: justify;\">9 &#8211; N\u00e3o realizar bochechos nos 4 primeiros dias;<\/p>\n<p style=\"text-align: justify;\">10\u00a0&#8211; Promover uma rigorosa higieniza\u00e7\u00e3o da cavidade bucal, optando por escova de cerdas macias, mas utilizando muito pouca quantidade de creme dental para reduzir a forma\u00e7\u00e3o de espuma;<\/p>\n<p style=\"text-align: justify;\">11 &#8211; Lavar a cavidade bucal com \u00e1gua, de prefer\u00eancia gelada, banhando com delicadeza a \u00e1rea operada e evitar cuspir, assim como evitar agita\u00e7\u00f5es ou esfor\u00e7os de modo a remover cuidadosamente a espuma da boca, sem perturbar o co\u00e1gulo sangu\u00edneo que protege a ferida cir\u00fargica;<\/p>\n<p style=\"text-align: justify;\">12 &#8211; Utilizar um cotonete embebido de \u00e1gua filtrada ou antiss\u00e9ptico bucal \u00e0 base de <a href=\"https:\/\/www.tuasaude.com\/clorexidina-merthiolate\/\">clorexidina<\/a> e sem \u00e1lcool, para remover muito delicadamente res\u00edduos alimentares e bact\u00e9rias bucais que aderem-se aos pontos, tornando-os sujos e infectados, situa\u00e7\u00f5es em que passam a apresentar colora\u00e7\u00e3o branca ou amarelada;<\/p>\n<p style=\"text-align: justify;\">13 &#8211; Nos dois ou tr\u00eas primeiros dias, aplicar compressas geladas pr\u00f3xima \u00e0 regi\u00e3o operada, protegendo a pele com uma toalha fina de algod\u00e3o ou agente hidratante para n\u00e3o queimar a pele. As compressas de gelo dever\u00e3o ser feitas por 20 minutos, seguidos, obrigatoriamente, de um per\u00edodo de descanso de outros 20 minutos; ap\u00f3s esse per\u00edodo, fazer nova aplica\u00e7\u00e3o de gelo por mais 20 minutos, e assim por diante, respeitando intervalos maiores de descanso ao longo do dia;<\/p>\n<p style=\"text-align: justify;\">14 &#8211; N\u00e3o levar o dedo ou qualquer objeto em contato com a \u00e1rea operada;<\/p>\n<p style=\"text-align: justify;\">15 &#8211; Em casos de sangramento no p\u00f3s-operat\u00f3rio, morder a regi\u00e3o operada com gaze est\u00e9ril, pressionando o local operado de forma ininterrupta;<\/p>\n<p style=\"text-align: justify;\">16 &#8211; \u00c9 normal a sensa\u00e7\u00e3o de gosto de sangue com saliva na boca, e um sangramento pequeno na primeira noite. Para evitar que isso ocorra, recomenda-se dormir com a cabe\u00e7a mais alta do que o corpo, utilizando, por exemplo, dois travesseiros.<\/p>\n<p style=\"text-align: justify;\">17 &#8211; Em casos de pacientes fumantes, evitar fumar ou reduzir muito a quantidade de cigarros at\u00e9 a repara\u00e7\u00e3o da ferida cir\u00fargica..<\/p>\n<p style=\"text-align: justify;\">18 &#8211; Bebidas alco\u00f3licas s\u00e3o terminantemente proibidas;<\/p>\n<p style=\"text-align: justify;\">19 &#8211; Seguir rigorosamente a prescri\u00e7\u00e3o dos medicamentos elaborada pelo dentista;<\/p>\n<p style=\"text-align: justify;\">20 &#8211; N\u00e3o tentar remover os pontos em casa. Este procedimento deve ser realizado no consult\u00f3rio do profissional, inclusive para que ele avalie o status da cicatriza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><a class=\"dt-single-image\" href=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png\" data-dt-img-description=\"\"><img decoding=\"async\" class=\"aligncenter wp-image-10843 size-full\" src=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png\" alt=\"\" width=\"910\" height=\"272\" srcset=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11.png 910w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-300x90.png 300w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-768x230.png 768w, https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/08\/cabecalho-11-600x179.png 600w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"caldera-grid\" id=\"caldera_form_1\" data-cf-ver=\"1.9.7\" data-cf-form-id=\"CF5b00382b5a25d\"><div id=\"caldera_notices_1\" data-spinner=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-admin\/images\/spinner.gif\"><\/div><form data-instance=\"1\" class=\"CF5b00382b5a25d caldera_forms_form cfajax-trigger\" method=\"POST\" enctype=\"multipart\/form-data\" id=\"CF5b00382b5a25d_1\" data-form-id=\"CF5b00382b5a25d\" aria-label=\"FALE CONOSCO\" data-target=\"#caldera_notices_1\" data-template=\"#cfajax_CF5b00382b5a25d-tmpl\" data-cfajax=\"CF5b00382b5a25d\" data-load-element=\"_parent\" data-load-class=\"cf_processing\" data-post-disable=\"0\" data-action=\"cf_process_ajax_submit\" data-request=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cf-api\/CF5b00382b5a25d\" data-hiderows=\"true\">\r\n<input type=\"hidden\" id=\"_cf_verify_CF5b00382b5a25d\" name=\"_cf_verify\" value=\"89d6600eb4\"  data-nonce-time=\"1778683611\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/16307\" \/><div id=\"cf2-CF5b00382b5a25d_1\"><\/div><input type=\"hidden\" name=\"_cf_frm_id\" value=\"CF5b00382b5a25d\">\r\n<input type=\"hidden\" name=\"_cf_frm_ct\" value=\"1\">\r\n<input type=\"hidden\" name=\"cfajax\" value=\"CF5b00382b5a25d\">\r\n<input type=\"hidden\" name=\"_cf_cr_pst\" value=\"16307\">\r\n<div class=\"hide\" style=\"display:none; overflow:hidden;height:0;width:0;\">\r\n<label>Phone<\/label><input type=\"text\" name=\"phone\" value=\"\" autocomplete=\"off\">\r\n<\/div><div id=\"CF5b00382b5a25d_1-row-1\"  class=\"row  first_row\"><div  class=\"col-sm-12  single\"><div class=\"\"><\/div><\/div><\/div><div id=\"CF5b00382b5a25d_1-row-2\"  class=\"row \"><div  class=\"col-sm-4  first_col\"><div data-field-wrapper=\"fld_8768091\" class=\"form-group\" id=\"fld_8768091_1-wrap\">\r\n\t<label id=\"fld_8768091Label\" for=\"fld_8768091_1\" class=\"control-label\">Nome <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_8768091\" class=\" form-control\" id=\"fld_8768091_1\" name=\"fld_8768091\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_8768091Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_9286608\" class=\"form-group\" id=\"fld_9286608_1-wrap\">\r\n\t<label id=\"fld_9286608Label\" for=\"fld_9286608_1\" class=\"control-label\">WhatsApp<\/label>\r\n\t<div class=\"\">\r\n\t\t<input    type=\"text\" data-field=\"fld_9286608\" class=\" form-control\" id=\"fld_9286608_1\" name=\"fld_9286608\" value=\"\" data-type=\"text\"   aria-labelledby=\"fld_9286608Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<\/div><div  class=\"col-sm-4 \"><div data-field-wrapper=\"fld_9970286\" class=\"form-group\" id=\"fld_9970286_1-wrap\">\r\n\t<label id=\"fld_9970286Label\" for=\"fld_9970286_1\" class=\"control-label\">Telefone <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_9970286\" class=\" form-control\" id=\"fld_9970286_1\" name=\"fld_9970286\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_9970286Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_8026901\" class=\"form-group\" id=\"fld_8026901_1-wrap\">\r\n\t<label id=\"fld_8026901Label\" for=\"fld_8026901_1\" class=\"control-label\">Como nos Conheceu?<\/label>\r\n\t<div class=\"\">\r\n\t\t<select name=\"fld_8026901\" value=\"opt1754659\" data-field=\"fld_8026901\" class=\"form-control\" id=\"fld_8026901_1\"    aria-labelledby=\"fld_8026901Label\" >\n\t\t\t\t\t\t\t<option value=\"Google\" selected=\"selected\" data-calc-value=\"Google\" >\n\t\t\t\t\t\tGoogle\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Facebook\"  data-calc-value=\"Facebook\" >\n\t\t\t\t\t\tFacebook\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Instagram\"  data-calc-value=\"Instagram\" >\n\t\t\t\t\t\tInstagram\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Indica\u00e7\u00e3o\"  data-calc-value=\"Indica\u00e7\u00e3o\" >\n\t\t\t\t\t\tIndica\u00e7\u00e3o\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Placa\"  data-calc-value=\"Placa\" >\n\t\t\t\t\t\tPlaca\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Outros\"  data-calc-value=\"Outros\" >\n\t\t\t\t\t\tOutros\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t<\/div>\r\n<\/div>\r\n<\/div><div  class=\"col-sm-4  last_col\"><div data-field-wrapper=\"fld_6009157\" class=\"form-group\" id=\"fld_6009157_1-wrap\">\r\n\t<label id=\"fld_6009157Label\" for=\"fld_6009157_1\" class=\"control-label\">Endere\u00e7o de E-mail <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"email\" data-field=\"fld_6009157\" class=\" form-control\" id=\"fld_6009157_1\" name=\"fld_6009157\" value=\"\" data-type=\"email\" aria-required=\"true\"   aria-labelledby=\"fld_6009157Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_2601416\" class=\"form-group\" id=\"fld_2601416_1-wrap\">\r\n\t<label id=\"fld_2601416Label\" for=\"fld_2601416_1\" class=\"control-label\">Que Tratamento Deseja Realizar?<\/label>\r\n\t<div class=\"\">\r\n\t\t<select name=\"fld_2601416\" value=\"\" data-field=\"fld_2601416\" class=\"form-control\" id=\"fld_2601416_1\"    aria-labelledby=\"fld_2601416Label\" >\n\t\t<option value=\"\"><\/option>\r\n\t\t\t\t\t<option value=\"Harmoniza\u00e7\u00e3o Orofacial\"  data-calc-value=\"Harmoniza\u00e7\u00e3o Orofacial\" >\n\t\t\t\t\t\tHarmoniza\u00e7\u00e3o Orofacial\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Botox e Preenchimento Facial\"  data-calc-value=\"Botox e Preenchimento Facial\" >\n\t\t\t\t\t\tBotox e Preenchimento Facial\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Bichectomia\"  data-calc-value=\"Bichectomia\" >\n\t\t\t\t\t\tBichectomia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Lipo de Papada\"  data-calc-value=\"Lipo de Papada\" >\n\t\t\t\t\t\tLipo de Papada\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Jato de Plasma\"  data-calc-value=\"Jato de Plasma\" >\n\t\t\t\t\t\tJato de Plasma\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Odontologia Est\u00e9tica\"  data-calc-value=\"Odontologia Est\u00e9tica\" >\n\t\t\t\t\t\tOdontologia Est\u00e9tica\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Rinomodela\u00e7\u00e3o\"  data-calc-value=\"Rinomodela\u00e7\u00e3o\" >\n\t\t\t\t\t\tRinomodela\u00e7\u00e3o\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Implantes Dent\u00e1rios\"  data-calc-value=\"Implantes Dent\u00e1rios\" >\n\t\t\t\t\t\tImplantes Dent\u00e1rios\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Clareamento Dental\"  data-calc-value=\"Clareamento Dental\" >\n\t\t\t\t\t\tClareamento Dental\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Ortodontia\"  data-calc-value=\"Ortodontia\" >\n\t\t\t\t\t\tOrtodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Endodontia\"  data-calc-value=\"Endodontia\" >\n\t\t\t\t\t\tEndodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Pr\u00f3tese Dental\"  data-calc-value=\"Pr\u00f3tese Dental\" >\n\t\t\t\t\t\tPr\u00f3tese Dental\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Periodontia\"  data-calc-value=\"Periodontia\" >\n\t\t\t\t\t\tPeriodontia\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t\t<option value=\"Cirurgia Oral\"  data-calc-value=\"Cirurgia Oral\" >\n\t\t\t\t\t\tCirurgia Oral\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t<\/div>\r\n<\/div>\r\n<\/div><\/div><div id=\"CF5b00382b5a25d_1-row-3\"  class=\"row \"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_8340154\" class=\"form-group\" id=\"fld_8340154_1-wrap\">\r\n\t<label id=\"fld_8340154Label\" for=\"fld_8340154_1\" class=\"control-label\">Sua Mensagem<\/label>\r\n\t<div class=\"\">\r\n\t\t<textarea name=\"fld_8340154\" value=\"\" data-field=\"fld_8340154\" class=\"form-control\" id=\"fld_8340154_1\" rows=\"4\"    aria-labelledby=\"fld_8340154Label\" ><\/textarea>\n\t\t\t<\/div>\r\n<\/div>\r\n<div class=\"\"><p><\/p>\n<\/div><\/div><\/div><div id=\"CF5b00382b5a25d_1-row-4\"  class=\"row  last_row\"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_7908577\" class=\"form-group\" id=\"fld_7908577_1-wrap\">\r\n<div class=\"\">\r\n\t<input  class=\"btn btn-default\" type=\"submit\" name=\"fld_7908577\" id=\"fld_7908577_1\" value=\"Enviar Mensagem\" data-field=\"fld_7908577\"  >\n<\/div>\r\n<\/div>\r\n\t<input class=\"button_trigger_1\" type=\"hidden\" name=\"fld_7908577\" id=\"fld_7908577_1_btn\" value=\"\" data-field=\"fld_7908577\"  \/>\n<\/div><\/div><\/form>\r\n<\/div>\r\n\n<h2 style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria, Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul, Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul SP, Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Av. Yervant Kissajikian, Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul Interlagos,<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria &#8211; Introdu\u00e7\u00e3o: Os cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria devem ser muito bem detalhados pelo cirurgi\u00e3o-dentista, logo ap\u00f3s a conclus\u00e3o da cirurgia. Ap\u00f3s a extra\u00e7\u00e3o de um dente, a cicatriza\u00e7\u00e3o come\u00e7a imediatamente com o preenchimento do nosso pr\u00f3prio sangue no interior da cavidade \u00f3ssea deixada vazia pela raiz do dente extra\u00eddo. Como resultado desse processo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":16319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-odontologicos","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul SP - Odontologia Apeles Lemos<\/title>\n<meta name=\"description\" content=\"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria recomendados devem ser rigorosamente seguidos pelo paciente para evtar complica\u00e7\u00f5es p\u00f3s-operat\u00f3rias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991\"},\"headline\":\"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria\",\"datePublished\":\"2021-07-04T23:48:52+00:00\",\"dateModified\":\"2021-07-06T02:06:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\"},\"wordCount\":882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg\",\"articleSection\":[\"Artigos Odontol\u00f3gicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\",\"name\":\"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul SP - Odontologia Apeles Lemos\",\"isPartOf\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg\",\"datePublished\":\"2021-07-04T23:48:52+00:00\",\"dateModified\":\"2021-07-06T02:06:56+00:00\",\"description\":\"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria recomendados devem ser rigorosamente seguidos pelo paciente para evtar complica\u00e7\u00f5es p\u00f3s-operat\u00f3rias\",\"breadcrumb\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg\",\"contentUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg\",\"width\":1024,\"height\":768,\"caption\":\"CUIDADOS P\u00d3S-EXTRA\u00c7\u00c3O DENT\u00c1RIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\",\"name\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"description\":\"Refer\u00eancia h\u00e1 30 anos em Odontologia, Cl\u00ednica Odontol\u00f3gica, Cl\u00ednica Dent\u00e1ria e Dentista Zona Sul SP. Whats App: 9 4624-0000. Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"publisher\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization\",\"name\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png\",\"contentUrl\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png\",\"width\":443,\"height\":190,\"caption\":\"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471\"},\"image\":{\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/odontoapeles\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991\",\"name\":\"administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g\",\"caption\":\"administrador\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul SP - Odontologia Apeles Lemos","description":"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria recomendados devem ser rigorosamente seguidos pelo paciente para evtar complica\u00e7\u00f5es p\u00f3s-operat\u00f3rias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/","twitter_misc":{"Escrito por":"administrador","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#article","isPartOf":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/"},"author":{"name":"administrador","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991"},"headline":"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria","datePublished":"2021-07-04T23:48:52+00:00","dateModified":"2021-07-06T02:06:56+00:00","mainEntityOfPage":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/"},"wordCount":882,"commentCount":0,"publisher":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage"},"thumbnailUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg","articleSection":["Artigos Odontol\u00f3gicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/","name":"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria Zona Sul SP - Odontologia Apeles Lemos","isPartOf":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website"},"primaryImageOfPage":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage"},"thumbnailUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg","datePublished":"2021-07-04T23:48:52+00:00","dateModified":"2021-07-06T02:06:56+00:00","description":"Cuidados p\u00f3s-extra\u00e7\u00e3o dent\u00e1ria recomendados devem ser rigorosamente seguidos pelo paciente para evtar complica\u00e7\u00f5es p\u00f3s-operat\u00f3rias","breadcrumb":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#primaryimage","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg","contentUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2021\/07\/tooth-extraction.jpg","width":1024,"height":768,"caption":"CUIDADOS P\u00d3S-EXTRA\u00c7\u00c3O DENT\u00c1RIA"},{"@type":"BreadcrumbList","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/cuidados-pos-extracao-dentaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/"},{"@type":"ListItem","position":2,"name":"Cuidados P\u00f3s-Extra\u00e7\u00e3o Dent\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#website","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/","name":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","description":"Refer\u00eancia h\u00e1 30 anos em Odontologia, Cl\u00ednica Odontol\u00f3gica, Cl\u00ednica Dent\u00e1ria e Dentista Zona Sul SP. Whats App: 9 4624-0000. Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","publisher":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#organization","name":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/","url":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png","contentUrl":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-content\/uploads\/2018\/05\/logo.png","width":443,"height":190,"caption":"Dentista Zona Sul SP - Odontologia Apeles Lemos - 5563-5471"},"image":{"@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/odontoapeles"]},{"@type":"Person","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/e05aefb4aac5b48d28fe5ef123d5e991","name":"administrador","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3089e6fb36c5ac23fe49c3206f06570?s=96&d=mm&r=g","caption":"administrador"}}]}},"_links":{"self":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/16307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/comments?post=16307"}],"version-history":[{"count":0,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/posts\/16307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/media\/16319"}],"wp:attachment":[{"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/media?parent=16307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/categories?post=16307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/odontoapeles.com.br\/dentista\/clinica-odontologica\/zona-sul\/wp-json\/wp\/v2\/tags?post=16307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}